﻿{"id":601,"date":"2024-04-10T14:26:00","date_gmt":"2024-04-10T17:26:00","guid":{"rendered":"https:\/\/cmas.santarosa.rs.gov.br\/?p=601"},"modified":"2024-05-14T14:35:42","modified_gmt":"2024-05-14T17:35:42","slug":"plano-de-acao-reprogramacao-saldo-financeiro-2023","status":"publish","type":"post","link":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2024\/04\/10\/plano-de-acao-reprogramacao-saldo-financeiro-2023\/","title":{"rendered":"Plano de A\u00e7\u00e3o (reprograma\u00e7\u00e3o saldo financeiro 2023)"},"content":{"rendered":"<ul class=\" wp-block-archives-list wp-block-archives\">\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2026\/05\/'>maio 2026<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2026\/04\/'>abril 2026<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2026\/02\/'>fevereiro 2026<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/12\/'>dezembro 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/11\/'>novembro 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/10\/'>outubro 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/09\/'>setembro 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/08\/'>agosto 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/07\/'>julho 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/06\/'>junho 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/05\/'>maio 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/04\/'>abril 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/03\/'>mar\u00e7o 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2025\/02\/'>fevereiro 2025<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2024\/12\/'>dezembro 2024<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2024\/11\/'>novembro 2024<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2024\/10\/'>outubro 2024<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2024\/08\/'>agosto 2024<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2024\/07\/'>julho 2024<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2024\/06\/'>junho 2024<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2024\/05\/'>maio 2024<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2024\/04\/'>abril 2024<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/12\/'>dezembro 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/11\/'>novembro 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/10\/'>outubro 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/09\/'>setembro 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/08\/'>agosto 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/07\/'>julho 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/06\/'>junho 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/05\/'>maio 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/04\/'>abril 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/03\/'>mar\u00e7o 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2023\/02\/'>fevereiro 2023<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2022\/12\/'>dezembro 2022<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2022\/11\/'>novembro 2022<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2022\/10\/'>outubro 2022<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2022\/08\/'>agosto 2022<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2022\/07\/'>julho 2022<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2022\/06\/'>junho 2022<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2022\/05\/'>maio 2022<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2022\/03\/'>mar\u00e7o 2022<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2022\/02\/'>fevereiro 2022<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2022\/01\/'>janeiro 2022<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/12\/'>dezembro 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/11\/'>novembro 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/10\/'>outubro 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/09\/'>setembro 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/08\/'>agosto 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/06\/'>junho 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/05\/'>maio 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/04\/'>abril 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/03\/'>mar\u00e7o 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/02\/'>fevereiro 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2021\/01\/'>janeiro 2021<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2020\/12\/'>dezembro 2020<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2018\/11\/'>novembro 2018<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2017\/11\/'>novembro 2017<\/a><\/li>\n\t<li><a href='https:\/\/cmas.santarosa.rs.gov.br\/index.php\/2016\/02\/'>fevereiro 2016<\/a><\/li>\n<\/ul>\n\n\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/cmas.santarosa.rs.gov.br\/wp-content\/uploads\/2024\/05\/Plano-de-acao-cmas_240514_141637.pdf\" type=\"application\/pdf\" style=\"width:100%;height:200px\" aria-label=\"Incorporado de Plano-de-acao-cmas_240514_141637.\"><\/object><a id=\"wp-block-file--media-b1e5415e-f262-47eb-b454-fe149093c6d2\" href=\"https:\/\/cmas.santarosa.rs.gov.br\/wp-content\/uploads\/2024\/05\/Plano-de-acao-cmas_240514_141637.pdf\">Plano-de-acao-cmas_240514_141637<\/a><a href=\"https:\/\/cmas.santarosa.rs.gov.br\/wp-content\/uploads\/2024\/05\/Plano-de-acao-cmas_240514_141637.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-b1e5415e-f262-47eb-b454-fe149093c6d2\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/601"}],"collection":[{"href":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=601"}],"version-history":[{"count":1,"href":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/601\/revisions"}],"predecessor-version":[{"id":603,"href":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/601\/revisions\/603"}],"wp:attachment":[{"href":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cmas.santarosa.rs.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}